{"id":3532,"date":"2023-12-20T15:44:33","date_gmt":"2023-12-20T18:44:33","guid":{"rendered":"https:\/\/website.maian.com.br\/?post_type=segmentos&#038;p=3532"},"modified":"2024-05-23T10:16:24","modified_gmt":"2024-05-23T13:16:24","slug":"espalhante-ecotech","status":"publish","type":"segmentos","link":"https:\/\/website.maian.com.br\/en\/segmentos\/espalhante-ecotech\/","title":{"rendered":"Adjuvante Espalhante Ecotech Siliconado"},"featured_media":4184,"template":"","categoria-de-segmentos":[46,36,51],"class_list":["post-3532","segmentos","type-segmentos","status-publish","has-post-thumbnail","hentry","categoria-de-segmentos-especialidades-agro","categoria-de-segmentos-maian-especialidades","categoria-de-segmentos-produtos-maian-agro"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.7 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Adjuvante Espalhante Ecotech Siliconado - Maian<\/title>\n<meta name=\"description\" content=\"Adjuvante Espalhante Ecotech Siliconado da Maian: mat\u00e9ria-prima para formula\u00e7\u00f5es. Consulte aplica\u00e7\u00f5es e informa\u00e7\u00f5es t\u00e9cnicas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/website.maian.com.br\/en\/segmentos\/espalhante-ecotech\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adjuvante Espalhante Ecotech Siliconado - Maian\" \/>\n<meta property=\"og:description\" content=\"Adjuvante Espalhante Ecotech Siliconado da Maian: mat\u00e9ria-prima para formula\u00e7\u00f5es. Consulte aplica\u00e7\u00f5es e informa\u00e7\u00f5es t\u00e9cnicas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/website.maian.com.br\/en\/segmentos\/espalhante-ecotech\/\" \/>\n<meta property=\"og:site_name\" content=\"Maian\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/maianoficial\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-23T13:16:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/website.maian.com.br\/wp-content\/uploads\/2023\/12\/23.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/website.maian.com.br\\\/segmentos\\\/espalhante-ecotech\\\/\",\"url\":\"https:\\\/\\\/website.maian.com.br\\\/segmentos\\\/espalhante-ecotech\\\/\",\"name\":\"Adjuvante Espalhante Ecotech Siliconado - Maian\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/website.maian.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/website.maian.com.br\\\/segmentos\\\/espalhante-ecotech\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/website.maian.com.br\\\/segmentos\\\/espalhante-ecotech\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/website.maian.com.br\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/23.jpg\",\"datePublished\":\"2023-12-20T18:44:33+00:00\",\"dateModified\":\"2024-05-23T13:16:24+00:00\",\"description\":\"Adjuvante Espalhante Ecotech Siliconado da Maian: mat\u00e9ria-prima para formula\u00e7\u00f5es. Consulte aplica\u00e7\u00f5es e informa\u00e7\u00f5es t\u00e9cnicas.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/website.maian.com.br\\\/segmentos\\\/espalhante-ecotech\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/website.maian.com.br\\\/segmentos\\\/espalhante-ecotech\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/website.maian.com.br\\\/segmentos\\\/espalhante-ecotech\\\/#primaryimage\",\"url\":\"https:\\\/\\\/website.maian.com.br\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/23.jpg\",\"contentUrl\":\"https:\\\/\\\/website.maian.com.br\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/23.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/website.maian.com.br\\\/segmentos\\\/espalhante-ecotech\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/website.maian.com.br\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Segmentos\",\"item\":\"https:\\\/\\\/website.maian.com.br\\\/segmentos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adjuvante Espalhante Ecotech Siliconado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/website.maian.com.br\\\/#website\",\"url\":\"https:\\\/\\\/website.maian.com.br\\\/\",\"name\":\"Maian\",\"description\":\"Inovadora por Natureza\",\"publisher\":{\"@id\":\"https:\\\/\\\/website.maian.com.br\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/website.maian.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/website.maian.com.br\\\/#organization\",\"name\":\"Maian\",\"url\":\"https:\\\/\\\/website.maian.com.br\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/website.maian.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/website.maian.com.br\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logosocial.png\",\"contentUrl\":\"https:\\\/\\\/website.maian.com.br\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/logosocial.png\",\"width\":200,\"height\":200,\"caption\":\"Maian\"},\"image\":{\"@id\":\"https:\\\/\\\/website.maian.com.br\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/maianoficial\",\"https:\\\/\\\/www.instagram.com\\\/maianoficial\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/maian\\\/?originalSubdomain=br\",\"https:\\\/\\\/www.youtube.com\\\/@maian-inovadorapornatureza2335\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Adjuvante Espalhante Ecotech Siliconado - Maian","description":"Adjuvante Espalhante Ecotech Siliconado da Maian: mat\u00e9ria-prima para formula\u00e7\u00f5es. Consulte aplica\u00e7\u00f5es e informa\u00e7\u00f5es t\u00e9cnicas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/website.maian.com.br\/en\/segmentos\/espalhante-ecotech\/","og_locale":"en_US","og_type":"article","og_title":"Adjuvante Espalhante Ecotech Siliconado - Maian","og_description":"Adjuvante Espalhante Ecotech Siliconado da Maian: mat\u00e9ria-prima para formula\u00e7\u00f5es. Consulte aplica\u00e7\u00f5es e informa\u00e7\u00f5es t\u00e9cnicas.","og_url":"https:\/\/website.maian.com.br\/en\/segmentos\/espalhante-ecotech\/","og_site_name":"Maian","article_publisher":"https:\/\/www.facebook.com\/maianoficial","article_modified_time":"2024-05-23T13:16:24+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/website.maian.com.br\/wp-content\/uploads\/2023\/12\/23.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/website.maian.com.br\/segmentos\/espalhante-ecotech\/","url":"https:\/\/website.maian.com.br\/segmentos\/espalhante-ecotech\/","name":"Adjuvante Espalhante Ecotech Siliconado - Maian","isPartOf":{"@id":"https:\/\/website.maian.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/website.maian.com.br\/segmentos\/espalhante-ecotech\/#primaryimage"},"image":{"@id":"https:\/\/website.maian.com.br\/segmentos\/espalhante-ecotech\/#primaryimage"},"thumbnailUrl":"https:\/\/website.maian.com.br\/wp-content\/uploads\/2023\/12\/23.jpg","datePublished":"2023-12-20T18:44:33+00:00","dateModified":"2024-05-23T13:16:24+00:00","description":"Adjuvante Espalhante Ecotech Siliconado da Maian: mat\u00e9ria-prima para formula\u00e7\u00f5es. Consulte aplica\u00e7\u00f5es e informa\u00e7\u00f5es t\u00e9cnicas.","breadcrumb":{"@id":"https:\/\/website.maian.com.br\/segmentos\/espalhante-ecotech\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/website.maian.com.br\/segmentos\/espalhante-ecotech\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/website.maian.com.br\/segmentos\/espalhante-ecotech\/#primaryimage","url":"https:\/\/website.maian.com.br\/wp-content\/uploads\/2023\/12\/23.jpg","contentUrl":"https:\/\/website.maian.com.br\/wp-content\/uploads\/2023\/12\/23.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/website.maian.com.br\/segmentos\/espalhante-ecotech\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/website.maian.com.br\/"},{"@type":"ListItem","position":2,"name":"Segmentos","item":"https:\/\/website.maian.com.br\/segmentos\/"},{"@type":"ListItem","position":3,"name":"Adjuvante Espalhante Ecotech Siliconado"}]},{"@type":"WebSite","@id":"https:\/\/website.maian.com.br\/#website","url":"https:\/\/website.maian.com.br\/","name":"Maian","description":"Inovadora por Natureza","publisher":{"@id":"https:\/\/website.maian.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/website.maian.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/website.maian.com.br\/#organization","name":"Maian","url":"https:\/\/website.maian.com.br\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/website.maian.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/website.maian.com.br\/wp-content\/uploads\/2024\/01\/logosocial.png","contentUrl":"https:\/\/website.maian.com.br\/wp-content\/uploads\/2024\/01\/logosocial.png","width":200,"height":200,"caption":"Maian"},"image":{"@id":"https:\/\/website.maian.com.br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/maianoficial","https:\/\/www.instagram.com\/maianoficial\/","https:\/\/www.linkedin.com\/company\/maian\/?originalSubdomain=br","https:\/\/www.youtube.com\/@maian-inovadorapornatureza2335"]}]}},"_links":{"self":[{"href":"https:\/\/website.maian.com.br\/en\/wp-json\/wp\/v2\/segmentos\/3532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/website.maian.com.br\/en\/wp-json\/wp\/v2\/segmentos"}],"about":[{"href":"https:\/\/website.maian.com.br\/en\/wp-json\/wp\/v2\/types\/segmentos"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/website.maian.com.br\/en\/wp-json\/wp\/v2\/media\/4184"}],"wp:attachment":[{"href":"https:\/\/website.maian.com.br\/en\/wp-json\/wp\/v2\/media?parent=3532"}],"wp:term":[{"taxonomy":"categoria-de-segmentos","embeddable":true,"href":"https:\/\/website.maian.com.br\/en\/wp-json\/wp\/v2\/categoria-de-segmentos?post=3532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}